{"id":47735,"date":"2022-06-14T10:24:37","date_gmt":"2022-06-14T10:24:37","guid":{"rendered":"https:\/\/www.polidesign.net\/?post_type=eventi&#038;p=47735"},"modified":"2022-06-15T09:20:35","modified_gmt":"2022-06-15T09:20:35","slug":"il-24-giugno-a-pesaro-e-linnovation-day","status":"publish","type":"eventi","link":"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/","title":{"rendered":"IL 24 GIUGNO A PESARO \u00c8 L\u2019INNOVATION DAY"},"featured_media":47832,"template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IL 24 GIUGNO A PESARO \u00c8 L\u2019INNOVATION DAY &bull; POLI.design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL 24 GIUGNO A PESARO \u00c8 L\u2019INNOVATION DAY &bull; POLI.design\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/\" \/>\n<meta property=\"og:site_name\" content=\"POLI.design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/polidesignmilano\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-15T09:20:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@POLI_design\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.polidesign.net\/it\/#organization\",\"name\":\"POLI.design\",\"url\":\"https:\/\/www.polidesign.net\/it\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/polidesignmilano\",\"https:\/\/www.instagram.com\/polidesign\/\",\"https:\/\/www.linkedin.com\/company\/polidesign-milano\",\"https:\/\/www.youtube.com\/user\/POLIdesign\",\"https:\/\/twitter.com\/POLI_design\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.polidesign.net\/it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.polidesign.net\/wp-content\/uploads\/2020\/10\/Logo-Polidesign-14.svg\",\"width\":182,\"height\":36,\"caption\":\"POLI.design\"},\"image\":{\"@id\":\"https:\/\/www.polidesign.net\/it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.polidesign.net\/it\/#website\",\"url\":\"https:\/\/www.polidesign.net\/it\/\",\"name\":\"POLI.design\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.polidesign.net\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.polidesign.net\/it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/#webpage\",\"url\":\"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/\",\"name\":\"IL 24 GIUGNO A PESARO \\u00c8 L\\u2019INNOVATION DAY &bull; POLI.design\",\"isPartOf\":{\"@id\":\"https:\/\/www.polidesign.net\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/#primaryimage\"},\"datePublished\":\"2022-06-14T10:24:37+00:00\",\"dateModified\":\"2022-06-15T09:20:35+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","acf":{"tipologia_evento":false,"relazioni":{"corso":"","area_formazione":false,"tipologia_formazione":[{"term_id":55,"name":"Master","slug":"master","term_group":0,"term_taxonomy_id":55,"taxonomy":"formazione_type","description":"Master Universitari","parent":0,"count":80,"filter":"raw","term_order":"2"}],"settore":false,"tags_poli":false,"ways_of_innovation":false,"alumni":false,"people":""},"cover_title":"INNOVATION DAY ","cover_subTitle":" Arredo su misura, nautica e contract: una sfida per tutto il settore","cover_abstract":"<p>Venerd\u00ec 24 giugno al Cantiere Rossini di Pesaro con la partecipazione di Arianna Bionda, Architetto e Yacht Designer, Adjunct Professor at the School of Design al Politecnico di Milano e Vice Direttore del Master in Yacht Design del Politecnico di Milano, gestito da POLI.design. <\/p>\n","cover_image":{"ID":47832,"id":47832,"title":"Innovation Day_24giugno2022","filename":"WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","filesize":138163,"url":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","link":"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/attachment\/whatsapp-image-2022-06-15-at-11-14-24\/","alt":"","author":"39","description":"","caption":"","name":"whatsapp-image-2022-06-15-at-11-14-24","status":"inherit","uploaded_to":47735,"date":"2022-06-15 09:19:54","modified":"2022-06-15 09:20:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.polidesign.net\/wp-includes\/images\/media\/default.png","width":1000,"height":1000,"sizes":{"thumbnail":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24-300x300.jpeg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24-768x768.jpeg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","large-width":1000,"large-height":1000,"1536x1536":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","1536x1536-width":1000,"1536x1536-height":1000,"2048x2048":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","2048x2048-width":1000,"2048x2048-height":1000}},"cover_imageThumbnail":{"ID":47832,"id":47832,"title":"Innovation Day_24giugno2022","filename":"WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","filesize":138163,"url":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","link":"https:\/\/www.polidesign.net\/it\/eventi\/il-24-giugno-a-pesaro-e-linnovation-day\/attachment\/whatsapp-image-2022-06-15-at-11-14-24\/","alt":"","author":"39","description":"","caption":"","name":"whatsapp-image-2022-06-15-at-11-14-24","status":"inherit","uploaded_to":47735,"date":"2022-06-15 09:19:54","modified":"2022-06-15 09:20:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.polidesign.net\/wp-includes\/images\/media\/default.png","width":1000,"height":1000,"sizes":{"thumbnail":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24-300x300.jpeg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24-768x768.jpeg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","large-width":1000,"large-height":1000,"1536x1536":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","1536x1536-width":1000,"1536x1536-height":1000,"2048x2048":"https:\/\/www.polidesign.net\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-15-at-11.14.24.jpeg","2048x2048-width":1000,"2048x2048-height":1000}},"flexible":[{"acf_fc_layout":"simpleTitleText","layout_settings":{"color":"default","component_title":{"isActive":false,"testo":""}},"acfe_flexible_toggle":"","acfe_flexible_layout_title":"Simple Title + Text","numero_di_colonne":"1","content":{"occhiello":"UN EVENTO UNICO, DEDICATO AGLI SPECIALISTI DEL SETTORE ARREDO SU MISURA, NAUTICA E CONTRACT","title":"","title_style":"normal","text":"","":null,"azione_cta":"legacyLink","cta_style":"button","cta_align":"center","cta":{"title":"Programma completo e richiesta invito","url":"https:\/\/blog.planstudio.it\/innovation-day-2022","target":""},"titolo_cta":"","modali_disponibil":false,"hubspot_id":"","prefill_campo_richiesta":""},"content_right":{"occhiello":"","title":"","title_style":"normal","text":"","":null,"azione_cta":"","cta_style":"normal","cta_align":"left","cta":null,"titolo_cta":"","modali_disponibil":false,"hubspot_id":"","prefill_campo_richiesta":""}},{"acf_fc_layout":"simpleTitleText","layout_settings":{"color":"default","component_title":{"isActive":false,"testo":""}},"acfe_flexible_toggle":"","acfe_flexible_layout_title":"Simple Title + Text","numero_di_colonne":"1","content":{"occhiello":"","title":"","title_style":"normal","text":"<p><strong>Venerd\u00ec 24 giugno al Cantiere Rossini di Pesaro<\/strong> si terr\u00e0 l\u2019<strong>Innovation Da<\/strong>y, l\u2019evento nazionale dedicato al settore dell\u2019arredo su misura, nautica e contract, organizzato dalla software engineering Planstudio con la partnership di <strong>Bentley System<\/strong> e <strong>Cantiere Rossini<\/strong>.<\/p>\n<p>Studi di progettazione, architettura e ingegneria, aziende di produzione di interni, cantieri navali e nautici, general e interior contractor si incontreranno per affrontare assieme i temi dell\u2019innovazione tecnologica, del perfezionamento dei processi aziendali e della integrazione e collaborazione nell\u2019intera filiera.<\/p>\n<p>\u201cUn vero e proprio viaggio nel futuro del mondo della tecnologia\u201d &#8211; spiega la CEO dell\u2019azienda <strong>Roberta Franceschetti<\/strong> &#8211; \u201cattraverso la presentazione di processi innovativi per la creazione di un ecosistema che agevoli tutte le filiere interessate e garantisca la costante tracciabilit\u00e0 del dato e dell\u2019informazione nel processo produttivo\u201d.<\/p>\n<p>L\u2019evento sar\u00e0 suddiviso in <strong>tre sessioni<\/strong>, imperniate su altrettante tavole rotonde.<\/p>\n<p>\u201cDurante la mattinata\u201d &#8211; spiega il CTO di Planstudio <strong>Massimo Franceschetti<\/strong> &#8211; \u201cmostreremo come <strong>tecnologie<\/strong> e <strong>processi<\/strong> possono rendere i tempi di esecuzione di una commessa pi\u00f9 brevi, con una riduzione notevole di errori e il conseguente contenimento dei costi, con particolare attenzione ai processi BIM\u201d.<\/p>\n<p>Nel pomeriggio si parler\u00e0 di <strong>sostenibilit\u00e0 come processo di evoluzione verso l\u2019innovazione<\/strong> e come affrontare le nuove sfide con una vision del futuro.<br \/>\nCoordinati dal giornalista e scrittore <strong>Antonio Vettese<\/strong>, interverranno gli esperti di settore: <strong>Arianna Bionda<\/strong>, Architetto e Yacht Designer, Adjunct Professor at the School of Design al Politecnico di Milano; <strong>Sergio Cutolo<\/strong>, Ingegnere Navale, Yacht Designer fondatore di HydroTec;<br \/>\n<strong>Tilli Antonelli<\/strong>, Imprenditore, Project Designer Cantieri Sanlorenzo; <strong>Daniele Mazzon<\/strong>, Head of Transportation and Yacht Design di Pininfarina SpA; <strong>Vasco Buonpensiere<\/strong>, Co-owner e Sales &amp; Marketing Director del Cantiere delle Marche; <strong>Lorenzo Argento<\/strong>, Yacht Designer; <strong>Alfonso Postorino<\/strong>, Direttore del Cantiere Rossini.<\/p>\n<p>Nell\u2019ultima sessione <strong>Massimo e Roberta Franceschetti<\/strong> &#8211; fondatori di Planstudio &#8211; parleranno di orientamento strategico e roadmap dei nuovi prodotti per il miglioramento dei processi produttivi, dell\u2019importanza delle collaborazioni durante il ciclo di vita della commessa e di strumenti e progetti formativi per la creazione di nuove risorse professionali. Sar\u00e0 anche il momento per celebrare i <strong>25 anni<\/strong> <strong>di expertise<\/strong> di Planstudio, che l\u2019azienda mette a disposizione dei protagonisti del settore arredo su misura, nautico e contract.<\/p>\n<p>Nel corso della giornata, inoltre, presso l\u2019<strong>area espositiva<\/strong>, attraverso dimostrazioni guidate dal team tecnico e di ricerca &amp; sviluppo di Planstudio e partners, sar\u00e0 possibile confrontarsi sulle pi\u00f9 performanti soluzioni specifiche del settore per l\u2019ottimizzazione dei processi.<\/p>\n<p>&nbsp;<\/p>\n","":null,"azione_cta":"legacyLink","cta_style":"normal","cta_align":"left","cta":{"title":"Maggiori informazioni","url":"https:\/\/blog.planstudio.it\/innovation-day-2022","target":"_blank"},"titolo_cta":"","modali_disponibil":false,"hubspot_id":"","prefill_campo_richiesta":""},"content_right":{"occhiello":"","title":"","title_style":"normal","text":"","":null,"azione_cta":"","cta_style":"normal","cta_align":"left","cta":null,"titolo_cta":"","modali_disponibil":false,"hubspot_id":"","prefill_campo_richiesta":""}}],"people_formazione":""},"_links":{"self":[{"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/eventi\/47735"}],"collection":[{"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/eventi"}],"about":[{"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/types\/eventi"}],"version-history":[{"count":17,"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/eventi\/47735\/revisions"}],"predecessor-version":[{"id":47834,"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/eventi\/47735\/revisions\/47834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/media\/47832"}],"wp:attachment":[{"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/media?parent=47735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}