{"id":5593,"date":"2020-12-26T18:23:32","date_gmt":"2020-12-26T18:23:32","guid":{"rendered":"https:\/\/staging.polidesign.net\/formazione\/%formazione_area%\/%formazione_type%--lighting-design-with-ipog\/"},"modified":"2022-12-23T11:31:52","modified_gmt":"2022-12-23T11:31:52","slug":"lighting-design-with-ipog","status":"publish","type":"formazione","link":"https:\/\/www.polidesign.net\/it\/formazione\/product-design\/corso--lighting-design-with-ipog\/","title":{"rendered":"Lighting Design with IPOG"},"author":37,"featured_media":5592,"menu_order":383,"template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lighting Design with IPOG &bull; POLI.design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polidesign.net\/it\/formazione\/product-design\/corso--lighting-design-with-ipog\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lighting Design with IPOG &bull; POLI.design\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polidesign.net\/it\/formazione\/product-design\/corso--lighting-design-with-ipog\/\" \/>\n<meta property=\"og:site_name\" content=\"POLI.design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/polidesignmilano\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-23T11:31:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.polidesign.net\/wp-content\/uploads\/2020\/12\/26893359362_b0334f4be9_o-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@POLI_design\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.polidesign.net\/it\/#organization\",\"name\":\"POLI.design\",\"url\":\"https:\/\/www.polidesign.net\/it\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/polidesignmilano\",\"https:\/\/www.instagram.com\/polidesign\/\",\"https:\/\/www.linkedin.com\/company\/polidesign-milano\",\"https:\/\/www.youtube.com\/user\/POLIdesign\",\"https:\/\/twitter.com\/POLI_design\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.polidesign.net\/it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.polidesign.net\/wp-content\/uploads\/2020\/10\/Logo-Polidesign-14.svg\",\"width\":182,\"height\":36,\"caption\":\"POLI.design\"},\"image\":{\"@id\":\"https:\/\/www.polidesign.net\/it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.polidesign.net\/it\/#website\",\"url\":\"https:\/\/www.polidesign.net\/it\/\",\"name\":\"POLI.design\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.polidesign.net\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.polidesign.net\/it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.polidesign.net\/it\/formazione\/product-design\/corso--lighting-design-with-ipog\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.polidesign.net\/wp-content\/uploads\/2020\/12\/26893359362_b0334f4be9_o-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.polidesign.net\/it\/formazione\/product-design\/corso--lighting-design-with-ipog\/#webpage\",\"url\":\"https:\/\/www.polidesign.net\/it\/formazione\/product-design\/corso--lighting-design-with-ipog\/\",\"name\":\"Lighting Design with IPOG &bull; POLI.design\",\"isPartOf\":{\"@id\":\"https:\/\/www.polidesign.net\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.polidesign.net\/it\/formazione\/product-design\/corso--lighting-design-with-ipog\/#primaryimage\"},\"datePublished\":\"2020-12-26T18:23:32+00:00\",\"dateModified\":\"2022-12-23T11:31:52+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.polidesign.net\/it\/formazione\/product-design\/corso--lighting-design-with-ipog\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/formazione\/5593"}],"collection":[{"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/formazione"}],"about":[{"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/types\/formazione"}],"author":[{"embeddable":true,"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/users\/37"}],"version-history":[{"count":14,"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/formazione\/5593\/revisions"}],"predecessor-version":[{"id":62579,"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/formazione\/5593\/revisions\/62579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/media\/5592"}],"wp:attachment":[{"href":"https:\/\/www.polidesign.net\/it\/wp-json\/wp\/v2\/media?parent=5593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}